{"id":1852,"date":"2023-09-18T10:35:02","date_gmt":"2023-09-18T09:35:02","guid":{"rendered":"https:\/\/aboutasthma.org\/life\/el-asma-empeora-con-la-edad\/"},"modified":"2024-04-24T09:09:40","modified_gmt":"2024-04-24T08:09:40","slug":"el-asma-empeora-con-la-edad","status":"publish","type":"life","link":"https:\/\/aboutasthma.org\/es\/vida\/el-asma-empeora-con-la-edad\/","title":{"rendered":"\u00bfEl asma empeora con la edad?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1852\" class=\"elementor elementor-1852 elementor-138\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b1c133 e-flex e-con-boxed e-con e-parent\" data-id=\"5b1c133\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a31628 elementor-widget elementor-widget-text-editor\" data-id=\"1a31628\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>No se puede pasar por alto el riesgo de que el asma empeore con la edad. El envejecimiento y haber vivido con asma durante mucho tiempo pueden <a href=\"https:\/\/aboutasthma.org\/es\/symptoms\/how-does-asthma-affect-the-lungs\/\">disminuir la funci\u00f3n pulmonar<\/a>.  Esto se debe a la rigidez de la pared tor\u00e1cica, la reducci\u00f3n de la funci\u00f3n de los m\u00fasculos respiratorios, la p\u00e9rdida de elasticidad y los cambios permanentes en las paredes de las v\u00edas respiratorias.<\/p>\n<p>Si tiene usted 65 a\u00f1os o m\u00e1s, o si es el cuidador de una persona mayor, debe saber que el asma puede empeorar a medida que los pulmones envejecen. Los s\u00edntomas pueden ser m\u00e1s dif\u00edciles de distinguir, ya que se pueden atribuir al envejecimiento normal o estar vinculados a patolog\u00edas como enfermedades cardiovasculares, obesidad o epoc. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8e7152d e-flex e-con-boxed e-con e-parent\" data-id=\"8e7152d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39eb337 elementor-widget elementor-widget-heading\" data-id=\"39eb337\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Manejo del asma en personas mayores, cosas que debe saber<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0d0558 elementor-widget elementor-widget-text-editor\" data-id=\"e0d0558\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tomar otros medicamentos para tratar afecciones que no sean el asma tambi\u00e9n puede causar confusi\u00f3n. Adem\u00e1s, algunos f\u00e1rmacos pueden reaccionar con ciertos tratamientos, y otros, como los betabloqueantes que pueden recetarse para problemas card\u00edacos o como colirio para algunos tipos de glaucoma, son susceptibles de empeorar los s\u00edntomas del asma. <\/p>\n<p>Las personas de edad avanzada tambi\u00e9n pueden experimentar dificultades para <a href=\"https:\/\/aboutasthma.org\/es\/care\/tratamientos-para-el-asma\/\">usar inhaladores<\/a> porque la artritis o la debilidad muscular reducen su capacidad para respirar con fuerza suficiente como para recibir la medicina en cada inhalaci\u00f3n. Por lo tanto, es muy importante que los pacientes mayores verifiquen su t\u00e9cnica de inhalaci\u00f3n en cada consulta. El uso del mismo tipo de inhalador para diferentes medicamentos tambi\u00e9n puede mejorar la adherencia. <\/p>\n<p>El tratamiento del asma en adultos mayores puede ser complicado si tienen confusi\u00f3n mental o problemas de memoria. Hable con el personal sanitario sobre c\u00f3mo simplificar su tratamiento, con un dispositivo inhalador que puedan usar f\u00e1cilmente. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48a07ed tip box-title elementor-widget elementor-widget-text-editor\" data-id=\"48a07ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Manejar el asma en el envejecimiento<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f320f3b box-content elementor-widget elementor-widget-text-editor\" data-id=\"f320f3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Pida al personal sanitario recordatorios digitales de medicamentos para ayudarle a cumplir con su horario de medicaci\u00f3n.<\/li>\n<li>Utilice un horario impreso diario de medicaci\u00f3n y recordatorios de reloj despertador.<\/li>\n<li>Aseg\u00farese de que el plan de acci\u00f3n sea f\u00e1cil de leer y est\u00e9 escrito con un tama\u00f1o de letra grande, si es necesario.<\/li>\n<li>Verifique repetidamente la t\u00e9cnica de inhalaci\u00f3n con un farmac\u00e9utico o una enfermero de asma.<br \/>Informe a los profesionales de la salud sobre cualquier tratamiento que est\u00e9 tomando, incluso aquellos que pueda pensar que no est\u00e1n relacionados en absoluto, como las gotas para los ojos para el glaucoma, ya que pueden causar un aumento de los s\u00edntomas o ataques graves.<\/li>\n<li>Vac\u00fanese contra la gripe y la COVID-19, y hable con los sanitarios sobre la <a href=\"https:\/\/aboutasthma.org\/es\/care\/asma-covid-19-y-otras-infecciones\/\">vacuna antineumoc\u00f3cica<\/a>.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a1ef58 elementor-widget elementor-widget-text-editor\" data-id=\"0a1ef58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/aboutasthma.org\/es\/attacks\/como-ayudar-a-alguien-con-un-ataque-de-asma\/\">C\u00f3mo ayudar durante un ataque de asma <\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"helpful-block-content wth-theme-thumbs\" data-title=\"\">\r\n<ul>\r\n<li><span class=\"wth-title\">\u00bfTe ha resultado \u00fatil este contenido?\u00a0<\/span><\/li>\r\n<li><a data-post=\"1852\" data-post-url=\"https:\/\/aboutasthma.org\/es\/vida\/el-asma-empeora-con-la-edad\/\" data-post-title=\"\u00bfEl asma empeora con la edad?\" data-response=\"1\" href=\"#\" class=\"wth-green-btn icon-thumbs-o-up icon1-thumbs-o-up\"><\/a><a data-response=\"0\" data-post=\"1852\" data-post-url=\"https:\/\/aboutasthma.org\/es\/vida\/el-asma-empeora-con-la-edad\/\" data-post-title=\"\u00bfEl asma empeora con la edad?\" href=\"#\" class=\"wth-red-btn icon-thumbs-o-down icon1-thumbs-o-down\"><\/a><\/li>\r\n<\/ul>\r\n<\/div>","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"class_list":["post-1852","life","type-life","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"No se puede pasar por alto el riesgo de que el asma empeore con la edad. El envejecimiento y haber vivido con asma durante mucho tiempo pueden disminuir la funci\u00f3n pulmonar. Esto se debe a la rigidez de la pared tor\u00e1cica, la reducci\u00f3n de la funci\u00f3n de los m\u00fasculos respiratorios, la p\u00e9rdida de elasticidad y\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/aboutasthma.org\/es\/vida\/el-asma-empeora-con-la-edad\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"About Asthma Un sitio web para guiar a pacientes con asma y cuidadores\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00bfEl asma empeora con la edad? \u2013 About Asthma\" \/>\n\t\t<meta property=\"og:description\" content=\"No se puede pasar por alto el riesgo de que el asma empeore con la edad. El envejecimiento y haber vivido con asma durante mucho tiempo pueden disminuir la funci\u00f3n pulmonar. Esto se debe a la rigidez de la pared tor\u00e1cica, la reducci\u00f3n de la funci\u00f3n de los m\u00fasculos respiratorios, la p\u00e9rdida de elasticidad y\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/aboutasthma.org\/es\/vida\/el-asma-empeora-con-la-edad\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/aboutasthma.org\/wp-content\/uploads\/2023\/09\/image.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/aboutasthma.org\/wp-content\/uploads\/2023\/09\/image.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"440\" \/>\n\t\t<meta property=\"og:image:height\" content=\"141\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-09-18T09:35:02+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-04-24T08:09:40+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00bfEl asma empeora con la edad? \u2013 About Asthma\" \/>\n\t\t<meta name=\"twitter:description\" content=\"No se puede pasar por alto el riesgo de que el asma empeore con la edad. El envejecimiento y haber vivido con asma durante mucho tiempo pueden disminuir la funci\u00f3n pulmonar. Esto se debe a la rigidez de la pared tor\u00e1cica, la reducci\u00f3n de la funci\u00f3n de los m\u00fasculos respiratorios, la p\u00e9rdida de elasticidad y\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/aboutasthma.org\/wp-content\/uploads\/2023\/09\/image.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/vida\\\/el-asma-empeora-con-la-edad\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/vida\\\/#listItem\",\"name\":\"Vivir\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/vida\\\/#listItem\",\"position\":2,\"name\":\"Vivir\",\"item\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/vida\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/vida\\\/el-asma-empeora-con-la-edad\\\/#listItem\",\"name\":\"\\u00bfEl asma empeora con la edad?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/vida\\\/el-asma-empeora-con-la-edad\\\/#listItem\",\"position\":3,\"name\":\"\\u00bfEl asma empeora con la edad?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/vida\\\/#listItem\",\"name\":\"Vivir\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/#organization\",\"name\":\"About Asthma\",\"description\":\"Un sitio web para guiar a pacientes con asma y cuidadores\",\"url\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/aboutasthma.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/about-asthma.svg\",\"@id\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/vida\\\/el-asma-empeora-con-la-edad\\\/#organizationLogo\",\"width\":409,\"height\":120},\"image\":{\"@id\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/vida\\\/el-asma-empeora-con-la-edad\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/vida\\\/el-asma-empeora-con-la-edad\\\/#webpage\",\"url\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/vida\\\/el-asma-empeora-con-la-edad\\\/\",\"name\":\"\\u00bfEl asma empeora con la edad? \\u2013 About Asthma\",\"description\":\"No se puede pasar por alto el riesgo de que el asma empeore con la edad. El envejecimiento y haber vivido con asma durante mucho tiempo pueden disminuir la funci\\u00f3n pulmonar. Esto se debe a la rigidez de la pared tor\\u00e1cica, la reducci\\u00f3n de la funci\\u00f3n de los m\\u00fasculos respiratorios, la p\\u00e9rdida de elasticidad y\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/vida\\\/el-asma-empeora-con-la-edad\\\/#breadcrumblist\"},\"datePublished\":\"2023-09-18T10:35:02+01:00\",\"dateModified\":\"2024-04-24T09:09:40+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/\",\"name\":\"About Asthma\",\"description\":\"Un sitio web para guiar a pacientes con asma y cuidadores\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/aboutasthma.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00bfEl asma empeora con la edad? \u2013 About Asthma","description":"No se puede pasar por alto el riesgo de que el asma empeore con la edad. El envejecimiento y haber vivido con asma durante mucho tiempo pueden disminuir la funci\u00f3n pulmonar. Esto se debe a la rigidez de la pared tor\u00e1cica, la reducci\u00f3n de la funci\u00f3n de los m\u00fasculos respiratorios, la p\u00e9rdida de elasticidad y","canonical_url":"https:\/\/aboutasthma.org\/es\/vida\/el-asma-empeora-con-la-edad\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/aboutasthma.org\/es\/vida\/el-asma-empeora-con-la-edad\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/aboutasthma.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/aboutasthma.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/aboutasthma.org\/es\/vida\/#listItem","name":"Vivir"}},{"@type":"ListItem","@id":"https:\/\/aboutasthma.org\/es\/vida\/#listItem","position":2,"name":"Vivir","item":"https:\/\/aboutasthma.org\/es\/vida\/","nextItem":{"@type":"ListItem","@id":"https:\/\/aboutasthma.org\/es\/vida\/el-asma-empeora-con-la-edad\/#listItem","name":"\u00bfEl asma empeora con la edad?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/aboutasthma.org\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/aboutasthma.org\/es\/vida\/el-asma-empeora-con-la-edad\/#listItem","position":3,"name":"\u00bfEl asma empeora con la edad?","previousItem":{"@type":"ListItem","@id":"https:\/\/aboutasthma.org\/es\/vida\/#listItem","name":"Vivir"}}]},{"@type":"Organization","@id":"https:\/\/aboutasthma.org\/es\/#organization","name":"About Asthma","description":"Un sitio web para guiar a pacientes con asma y cuidadores","url":"https:\/\/aboutasthma.org\/es\/","logo":{"@type":"ImageObject","url":"https:\/\/aboutasthma.org\/wp-content\/uploads\/2023\/09\/about-asthma.svg","@id":"https:\/\/aboutasthma.org\/es\/vida\/el-asma-empeora-con-la-edad\/#organizationLogo","width":409,"height":120},"image":{"@id":"https:\/\/aboutasthma.org\/es\/vida\/el-asma-empeora-con-la-edad\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/aboutasthma.org\/es\/vida\/el-asma-empeora-con-la-edad\/#webpage","url":"https:\/\/aboutasthma.org\/es\/vida\/el-asma-empeora-con-la-edad\/","name":"\u00bfEl asma empeora con la edad? \u2013 About Asthma","description":"No se puede pasar por alto el riesgo de que el asma empeore con la edad. El envejecimiento y haber vivido con asma durante mucho tiempo pueden disminuir la funci\u00f3n pulmonar. Esto se debe a la rigidez de la pared tor\u00e1cica, la reducci\u00f3n de la funci\u00f3n de los m\u00fasculos respiratorios, la p\u00e9rdida de elasticidad y","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/aboutasthma.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/aboutasthma.org\/es\/vida\/el-asma-empeora-con-la-edad\/#breadcrumblist"},"datePublished":"2023-09-18T10:35:02+01:00","dateModified":"2024-04-24T09:09:40+01:00"},{"@type":"WebSite","@id":"https:\/\/aboutasthma.org\/es\/#website","url":"https:\/\/aboutasthma.org\/es\/","name":"About Asthma","description":"Un sitio web para guiar a pacientes con asma y cuidadores","inLanguage":"es-ES","publisher":{"@id":"https:\/\/aboutasthma.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"About Asthma Un sitio web para guiar a pacientes con asma y cuidadores","og:type":"article","og:title":"\u00bfEl asma empeora con la edad? \u2013 About Asthma","og:description":"No se puede pasar por alto el riesgo de que el asma empeore con la edad. El envejecimiento y haber vivido con asma durante mucho tiempo pueden disminuir la funci\u00f3n pulmonar. Esto se debe a la rigidez de la pared tor\u00e1cica, la reducci\u00f3n de la funci\u00f3n de los m\u00fasculos respiratorios, la p\u00e9rdida de elasticidad y","og:url":"https:\/\/aboutasthma.org\/es\/vida\/el-asma-empeora-con-la-edad\/","og:image":"https:\/\/aboutasthma.org\/wp-content\/uploads\/2023\/09\/image.png","og:image:secure_url":"https:\/\/aboutasthma.org\/wp-content\/uploads\/2023\/09\/image.png","og:image:width":440,"og:image:height":141,"article:published_time":"2023-09-18T09:35:02+00:00","article:modified_time":"2024-04-24T08:09:40+00:00","twitter:card":"summary_large_image","twitter:title":"\u00bfEl asma empeora con la edad? \u2013 About Asthma","twitter:description":"No se puede pasar por alto el riesgo de que el asma empeore con la edad. El envejecimiento y haber vivido con asma durante mucho tiempo pueden disminuir la funci\u00f3n pulmonar. Esto se debe a la rigidez de la pared tor\u00e1cica, la reducci\u00f3n de la funci\u00f3n de los m\u00fasculos respiratorios, la p\u00e9rdida de elasticidad y","twitter:image":"https:\/\/aboutasthma.org\/wp-content\/uploads\/2023\/09\/image.png"},"aioseo_meta_data":{"post_id":"1852","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-04-24 08:09:39","updated":"2026-08-05 16:12:24","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/aboutasthma.org\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u203a<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/aboutasthma.org\/es\/vida\/\" title=\"Vivir\">Vivir<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u203a<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00bfEl asma empeora con la edad?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/aboutasthma.org\/es\/"},{"label":"Vivir","link":"https:\/\/aboutasthma.org\/es\/vida\/"},{"label":"\u00bfEl asma empeora con la edad?","link":"https:\/\/aboutasthma.org\/es\/vida\/el-asma-empeora-con-la-edad\/"}],"_links":{"self":[{"href":"https:\/\/aboutasthma.org\/es\/wp-json\/wp\/v2\/life\/1852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aboutasthma.org\/es\/wp-json\/wp\/v2\/life"}],"about":[{"href":"https:\/\/aboutasthma.org\/es\/wp-json\/wp\/v2\/types\/life"}],"version-history":[{"count":3,"href":"https:\/\/aboutasthma.org\/es\/wp-json\/wp\/v2\/life\/1852\/revisions"}],"predecessor-version":[{"id":1855,"href":"https:\/\/aboutasthma.org\/es\/wp-json\/wp\/v2\/life\/1852\/revisions\/1855"}],"wp:attachment":[{"href":"https:\/\/aboutasthma.org\/es\/wp-json\/wp\/v2\/media?parent=1852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}